{"id":6079,"date":"2016-12-01T09:39:01","date_gmt":"2016-12-01T09:39:01","guid":{"rendered":"http:\/\/progresomicrofinanzas.org\/?p=6079"},"modified":"2017-11-17T13:17:17","modified_gmt":"2017-11-17T13:17:17","slug":"creacion-de-una-canasta-gratuita-de-servicios-financieros","status":"publish","type":"post","link":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/creacion-de-una-canasta-gratuita-de-servicios-financieros\/","title":{"rendered":"Canasta gratuita de servicios financieros"},"content":{"rendered":"<div class=\"pdfprnt-buttons pdfprnt-buttons-post pdfprnt-top-right\"><a href=\"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/posts\/6079?print=pdf\" class=\"pdfprnt-button pdfprnt-button-pdf\" target=\"_blank\" ><img decoding=\"async\" src=\"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/plugins\/pdf-print\/images\/pdf.png\" alt=\"image_pdf\" title=\"Ver PDF\" \/><\/a><a href=\"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/posts\/6079?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\" ><img decoding=\"async\" src=\"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/plugins\/pdf-print\/images\/print.png\" alt=\"image_print\" title=\"Imprimir contenido\" \/><\/a><\/div><p><span style=\"font-weight: 400;\">El presente Proyecto, radicado en la C\u00e1mara de Representantes de Colombia, propone crear una canasta de servicios financieros gratuitos asociados a las cuentas de ahorro, y a las tarjetas de d\u00e9bito y cr\u00e9dito. Esta canasta se ofrecer\u00eda por aquellas entidades que, estando autorizadas para captar recursos del p\u00fablico, cobren cuotas de manejo en los mencionados productos financieros.<\/span><\/p>\n<h4><strong>Servicios financieros gratuitos<\/strong><\/h4>\n<p><span style=\"font-weight: 400;\">En la propuesta inicial de este Proyecto se hab\u00eda establecido que la canasta estuviera formada por los tres productos y servicios m\u00e1s utilizados, relacionados con las cuentas de ahorro y tarjetas de cr\u00e9dito que conforman la canasta utilizada para el c\u00e1lculo del \u00cdndice de Precios al Consumidor Financiero (IPCF), fijada por la Superintendencia Financiera de Colombia. No obstante, en el informe de ponencia para el primer debate de este texto en la C\u00e1mara de Representantes, se modific\u00f3 la propuesta, eliminando el IPCF como referencia para el c\u00e1lculo de la canasta de servicios representativos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En su lugar, se estableci\u00f3 una lista de servicios financieros que se prestan con la apertura de una cuenta de ahorros, de entre los que las entidades deber\u00e1n escoger tres, que ser\u00e1n gratuitos cuando los bancos cobren cuotas de manejo por \u00e9stas. Adem\u00e1s, se establece una lista de servicios similar a la anterior, pero referida a las tarjetas de d\u00e9bito y cr\u00e9dito.<\/span><\/p>\n<h4><strong>Informaci\u00f3n a los usuarios<\/strong><\/h4>\n<p><span style=\"font-weight: 400;\">Por otro lado, en este Proyecto de ley se establece la obligaci\u00f3n de informar a sus usuarios de manera clara y oportuna, por parte de las entidades autorizadas para captar recursos del p\u00fablico, sobre la composici\u00f3n del paquete m\u00ednimo de productos y\/o servicios al que tendr\u00e1n acceso sin costo adicional en el respectivo mes. Para ello podr\u00e1n utilizar los canales habituales de comunicaci\u00f3n.<br \/>\n<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presente Proyecto, radicado en la C\u00e1mara de Representantes de Colombia, propone crear una canasta de servicios financieros gratuitos asociados a las cuentas de ahorro, y a las tarjetas de d\u00e9bito y cr\u00e9dito. Esta canasta se ofrecer\u00eda por aquellas entidades que, estando autorizadas para captar recursos del p\u00fablico, cobren cuotas de manejo en los mencionados [&hellip;]<\/p>\n","protected":false},"author":30,"featured_media":6081,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"tags":[211,1537,1543,208,299,1541,1538,1539,1540,260,1210,668,1542],"class_list":["post-6079","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-camara-de-representantes","tag-canasta-gratuita","tag-captacion-de-recursos","tag-colombia","tag-consumidor-financiero","tag-cuentas-de-ahorros","tag-cuotas-de-manejo","tag-indice-de-precios-al-consumidor-financiero","tag-ipcf","tag-productos-financieros","tag-servicios-financieros","tag-tarjetas-de-credito","tag-tarjetas-de-debito","numero-9m","seccion-legislacion-normas-publicadas-microfinanzas","pais-colombia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Canasta gratuita de servicios financieros<\/title>\n<meta name=\"description\" content=\"Creaci\u00f3n de una canasta de servicios financieros gratuitos asociados a cuentas de ahorro, tarjetas d\u00e9bito y cr\u00e9dito, cuando sobre dichos productos se cobre\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/creacion-de-una-canasta-gratuita-de-servicios-financieros\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Canasta gratuita de servicios financieros\" \/>\n<meta property=\"og:description\" content=\"Creaci\u00f3n de una canasta de servicios financieros gratuitos asociados a cuentas de ahorro, tarjetas d\u00e9bito y cr\u00e9dito, cuando sobre dichos productos se cobre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/creacion-de-una-canasta-gratuita-de-servicios-financieros\/\" \/>\n<meta property=\"og:site_name\" content=\"Progreso\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fundacionmicrofinanzasbbva\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-01T09:39:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-17T13:17:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/uploads\/2016\/10\/colombia-camera-repres1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"925\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"karessa Ramos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FMBBVA\" \/>\n<meta name=\"twitter:site\" content=\"@FMBBVA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"karessa Ramos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/creacion-de-una-canasta-gratuita-de-servicios-financieros\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/creacion-de-una-canasta-gratuita-de-servicios-financieros\\\/\"},\"author\":{\"name\":\"karessa Ramos\",\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#\\\/schema\\\/person\\\/4a3fe64f7988998aa5e22913c8147baf\"},\"headline\":\"Canasta gratuita de servicios financieros\",\"datePublished\":\"2016-12-01T09:39:01+00:00\",\"dateModified\":\"2017-11-17T13:17:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/creacion-de-una-canasta-gratuita-de-servicios-financieros\\\/\"},\"wordCount\":314,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/creacion-de-una-canasta-gratuita-de-servicios-financieros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/colombia-camera-repres1.jpg\",\"keywords\":[\"C\u00e1mara de Representantes\",\"canasta gratuita\",\"captaci\u00f3n de recursos\",\"Colombia\",\"consumidor financiero\",\"cuentas de ahorros\",\"cuotas de manejo\",\"\u00cdndice de Precios al Consumidor Financiero\",\"IPCF\",\"productos financieros\",\"Servicios Financieros\",\"tarjetas de cr\u00e9dito\",\"tarjetas de d\u00e9bito\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/creacion-de-una-canasta-gratuita-de-servicios-financieros\\\/\",\"url\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/creacion-de-una-canasta-gratuita-de-servicios-financieros\\\/\",\"name\":\"Canasta gratuita de servicios financieros\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/creacion-de-una-canasta-gratuita-de-servicios-financieros\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/creacion-de-una-canasta-gratuita-de-servicios-financieros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/colombia-camera-repres1.jpg\",\"datePublished\":\"2016-12-01T09:39:01+00:00\",\"dateModified\":\"2017-11-17T13:17:17+00:00\",\"description\":\"Creaci\u00f3n de una canasta de servicios financieros gratuitos asociados a cuentas de ahorro, tarjetas d\u00e9bito y cr\u00e9dito, cuando sobre dichos productos se cobre\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/creacion-de-una-canasta-gratuita-de-servicios-financieros\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/creacion-de-una-canasta-gratuita-de-servicios-financieros\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/creacion-de-una-canasta-gratuita-de-servicios-financieros\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/colombia-camera-repres1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/colombia-camera-repres1.jpg\",\"width\":925,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/creacion-de-una-canasta-gratuita-de-servicios-financieros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Canasta gratuita de servicios financieros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#website\",\"url\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/\",\"name\":\"Revista Progreso\",\"description\":\"Revista de Actualidad Jur\u00eddica\",\"publisher\":{\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#organization\"},\"alternateName\":\"Revista Progreso\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#organization\",\"name\":\"Revista Progreso\",\"alternateName\":\"Revista Progreso\",\"url\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Logo-FMBBVA-AZUL.png\",\"contentUrl\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Logo-FMBBVA-AZUL.png\",\"width\":6173,\"height\":1001,\"caption\":\"Revista Progreso\"},\"image\":{\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fundacionmicrofinanzasbbva\",\"https:\\\/\\\/x.com\\\/FMBBVA\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacin-microfinanzas-bbva\\\/\",\"https:\\\/\\\/www.instagram.com\\\/somosfmbbva\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#\\\/schema\\\/person\\\/4a3fe64f7988998aa5e22913c8147baf\",\"name\":\"karessa Ramos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2388109b4325a6fb9c892c3212e430cdc0835c8fc1c1a41f4cc2a3b175b81c5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2388109b4325a6fb9c892c3212e430cdc0835c8fc1c1a41f4cc2a3b175b81c5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2388109b4325a6fb9c892c3212e430cdc0835c8fc1c1a41f4cc2a3b175b81c5?s=96&d=mm&r=g\",\"caption\":\"karessa Ramos\"},\"url\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/author\\\/karessa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Canasta gratuita de servicios financieros","description":"Creaci\u00f3n de una canasta de servicios financieros gratuitos asociados a cuentas de ahorro, tarjetas d\u00e9bito y cr\u00e9dito, cuando sobre dichos productos se cobre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/creacion-de-una-canasta-gratuita-de-servicios-financieros\/","og_locale":"es_ES","og_type":"article","og_title":"Canasta gratuita de servicios financieros","og_description":"Creaci\u00f3n de una canasta de servicios financieros gratuitos asociados a cuentas de ahorro, tarjetas d\u00e9bito y cr\u00e9dito, cuando sobre dichos productos se cobre","og_url":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/creacion-de-una-canasta-gratuita-de-servicios-financieros\/","og_site_name":"Progreso","article_publisher":"https:\/\/www.facebook.com\/fundacionmicrofinanzasbbva","article_published_time":"2016-12-01T09:39:01+00:00","article_modified_time":"2017-11-17T13:17:17+00:00","og_image":[{"width":925,"height":800,"url":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/uploads\/2016\/10\/colombia-camera-repres1.jpg","type":"image\/jpeg"}],"author":"karessa Ramos","twitter_card":"summary_large_image","twitter_creator":"@FMBBVA","twitter_site":"@FMBBVA","twitter_misc":{"Escrito por":"karessa Ramos","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/creacion-de-una-canasta-gratuita-de-servicios-financieros\/#article","isPartOf":{"@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/creacion-de-una-canasta-gratuita-de-servicios-financieros\/"},"author":{"name":"karessa Ramos","@id":"https:\/\/34.249.117.129\/revistaprogreso\/#\/schema\/person\/4a3fe64f7988998aa5e22913c8147baf"},"headline":"Canasta gratuita de servicios financieros","datePublished":"2016-12-01T09:39:01+00:00","dateModified":"2017-11-17T13:17:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/creacion-de-una-canasta-gratuita-de-servicios-financieros\/"},"wordCount":314,"commentCount":0,"publisher":{"@id":"https:\/\/34.249.117.129\/revistaprogreso\/#organization"},"image":{"@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/creacion-de-una-canasta-gratuita-de-servicios-financieros\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/uploads\/2016\/10\/colombia-camera-repres1.jpg","keywords":["C\u00e1mara de Representantes","canasta gratuita","captaci\u00f3n de recursos","Colombia","consumidor financiero","cuentas de ahorros","cuotas de manejo","\u00cdndice de Precios al Consumidor Financiero","IPCF","productos financieros","Servicios Financieros","tarjetas de cr\u00e9dito","tarjetas de d\u00e9bito"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/creacion-de-una-canasta-gratuita-de-servicios-financieros\/","url":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/creacion-de-una-canasta-gratuita-de-servicios-financieros\/","name":"Canasta gratuita de servicios financieros","isPartOf":{"@id":"https:\/\/34.249.117.129\/revistaprogreso\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/creacion-de-una-canasta-gratuita-de-servicios-financieros\/#primaryimage"},"image":{"@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/creacion-de-una-canasta-gratuita-de-servicios-financieros\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/uploads\/2016\/10\/colombia-camera-repres1.jpg","datePublished":"2016-12-01T09:39:01+00:00","dateModified":"2017-11-17T13:17:17+00:00","description":"Creaci\u00f3n de una canasta de servicios financieros gratuitos asociados a cuentas de ahorro, tarjetas d\u00e9bito y cr\u00e9dito, cuando sobre dichos productos se cobre","breadcrumb":{"@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/creacion-de-una-canasta-gratuita-de-servicios-financieros\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/creacion-de-una-canasta-gratuita-de-servicios-financieros\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/creacion-de-una-canasta-gratuita-de-servicios-financieros\/#primaryimage","url":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/uploads\/2016\/10\/colombia-camera-repres1.jpg","contentUrl":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/uploads\/2016\/10\/colombia-camera-repres1.jpg","width":925,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/creacion-de-una-canasta-gratuita-de-servicios-financieros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/34.249.117.129\/revistaprogreso\/"},{"@type":"ListItem","position":2,"name":"Canasta gratuita de servicios financieros"}]},{"@type":"WebSite","@id":"https:\/\/34.249.117.129\/revistaprogreso\/#website","url":"https:\/\/34.249.117.129\/revistaprogreso\/","name":"Revista Progreso","description":"Revista de Actualidad Jur\u00eddica","publisher":{"@id":"https:\/\/34.249.117.129\/revistaprogreso\/#organization"},"alternateName":"Revista Progreso","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/34.249.117.129\/revistaprogreso\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/34.249.117.129\/revistaprogreso\/#organization","name":"Revista Progreso","alternateName":"Revista Progreso","url":"https:\/\/34.249.117.129\/revistaprogreso\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/34.249.117.129\/revistaprogreso\/#\/schema\/logo\/image\/","url":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/uploads\/2023\/09\/Logo-FMBBVA-AZUL.png","contentUrl":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/uploads\/2023\/09\/Logo-FMBBVA-AZUL.png","width":6173,"height":1001,"caption":"Revista Progreso"},"image":{"@id":"https:\/\/34.249.117.129\/revistaprogreso\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fundacionmicrofinanzasbbva","https:\/\/x.com\/FMBBVA","https:\/\/www.linkedin.com\/company\/fundacin-microfinanzas-bbva\/","https:\/\/www.instagram.com\/somosfmbbva\/"]},{"@type":"Person","@id":"https:\/\/34.249.117.129\/revistaprogreso\/#\/schema\/person\/4a3fe64f7988998aa5e22913c8147baf","name":"karessa Ramos","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a2388109b4325a6fb9c892c3212e430cdc0835c8fc1c1a41f4cc2a3b175b81c5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a2388109b4325a6fb9c892c3212e430cdc0835c8fc1c1a41f4cc2a3b175b81c5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2388109b4325a6fb9c892c3212e430cdc0835c8fc1c1a41f4cc2a3b175b81c5?s=96&d=mm&r=g","caption":"karessa Ramos"},"url":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/author\/karessa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/posts\/6079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/comments?post=6079"}],"version-history":[{"count":0,"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/posts\/6079\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/media\/6081"}],"wp:attachment":[{"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/media?parent=6079"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/tags?post=6079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}