{"id":12815,"date":"2018-12-07T12:50:23","date_gmt":"2018-12-07T12:50:23","guid":{"rendered":"http:\/\/progresomicrofinanzas.org\/?p=12815\/"},"modified":"2018-12-07T12:50:23","modified_gmt":"2018-12-07T12:50:23","slug":"modificacion-del-reglamento-gestion-conducta-mercado","status":"publish","type":"post","link":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/modificacion-del-reglamento-gestion-conducta-mercado\/","title":{"rendered":"Modificaci\u00f3n del reglamento de gesti\u00f3n de conducta de mercado"},"content":{"rendered":"<div class=\"pdfprnt-buttons pdfprnt-buttons-post pdfprnt-top-right\"><a href=\"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/posts\/12815?print=pdf\" class=\"pdfprnt-button pdfprnt-button-pdf\" target=\"_blank\" ><img decoding=\"async\" src=\"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/plugins\/pdf-print\/images\/pdf.png\" alt=\"image_pdf\" title=\"Ver PDF\" \/><\/a><a href=\"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/posts\/12815?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\" ><img decoding=\"async\" src=\"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/plugins\/pdf-print\/images\/print.png\" alt=\"image_print\" title=\"Imprimir contenido\" \/><\/a><\/div><p>Con la finalidad de incorporar disposiciones y establecer precisiones que permitan el desarrollo de la oferta de productos y servicios financieros en un entorno digital, as\u00ed como adecuar el alcance del marco normativo vigente considerando los productos y servicios ofrecidos por las empresas, al tama\u00f1o y volumen de sus operaciones, la Superintendencia de Banca, Seguros y AFP (SBS) public\u00f3 el pasado mes de octubre la modificaci\u00f3n del Reglamento de Gesti\u00f3n de Conducta de Mercado del Sistema Financiero, del Reglamento de Auditor\u00eda Interna, Reglamento de Tarjetas de Cr\u00e9dito y D\u00e9bito, del Manual de Contabilidad para las empresas del Sistema Financiero y de la Circular G-184-2015 sobre el Servicios de Atenci\u00f3n al Usuario.<\/p>\n<p><b>Mecanismos de seguridad<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Con las modificaciones introducidas al Reglamento de Gesti\u00f3n de Conducta de Mercado del Sistema Financiero se busca que las empresas del sistema financiero incrementen sus mecanismos de seguridad, para lo cual deber\u00e1n utilizar alg\u00fan factor de autenticaci\u00f3n con el fin de validar la identidad del cliente y dejar constancia de la aceptaci\u00f3n. Adem\u00e1s, las empresas deber\u00e1n acreditar la entrega al cliente, por cualquier medio, del n\u00famero de la resoluci\u00f3n mediante el cual la SBS aprob\u00f3 las cl\u00e1usulas generales correspondientes al contrato celebrado.<\/span><\/p>\n<p><b>Comunicaci\u00f3n con el cliente<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Por otra parte, la norma faculta a las empresas a utilizar medios de comunicaci\u00f3n f\u00edsicos o electr\u00f3nicos con el cliente y deber\u00e1n contar con canales de f\u00e1cil acceso para que los clientes puedan resolver el contrato, debiendo como m\u00ednimo contar con los mismos canales disponibles para la contrataci\u00f3n.<\/span><\/p>\n<p><b>Otras modificaciones<\/b><\/p>\n<p><span style=\"font-weight: 400;\">La resoluci\u00f3n modifica igualmente el Reglamento de Bancos de Inversi\u00f3n para eximirlo del Reglamento de Gesti\u00f3n de Conducta de Mercado, considerando la naturaleza de sus productos y clientes. Adem\u00e1s, con la publicaci\u00f3n de la Circular G-184-2015, se incluye en el Reporte Regulatorio los reclamos recibidos a trav\u00e9s de canales directos o en asociaci\u00f3n con el gremio.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la finalidad de incorporar disposiciones y establecer precisiones que permitan el desarrollo de la oferta de productos y servicios financieros en un entorno digital, as\u00ed como adecuar el alcance del marco normativo vigente considerando los productos y servicios ofrecidos por las empresas, al tama\u00f1o y volumen de sus operaciones, la Superintendencia de Banca, Seguros [&hellip;]<\/p>\n","protected":false},"author":30,"featured_media":12817,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"tags":[164,179,1906,3922,296,2274,3923,3921,3926,3925,240,317,3924,1435,200,305,277],"class_list":["post-12815","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-comunicacion","tag-reglamento","tag-canales","tag-clausulas-generales","tag-clientes","tag-conducta-de-mercado","tag-contratos","tag-digital","tag-entorno-digital","tag-mecanismos-de-seguridad","tag-mercado","tag-peru","tag-reporte-regulatorio","tag-resolucion","tag-sbs","tag-seguridad","tag-sistema-financiero","numero-17m","seccion-legislacion-normas-publicadas-gobierno-corporativo","pais-peru"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Modificaci\u00f3n del reglamento de gesti\u00f3n de conducta de mercado<\/title>\n<meta name=\"description\" content=\"La Resoluci\u00f3n SBS N\u00b0 3966-2018 modifica entre otros el Reglamento de Gesti\u00f3n de Conducta de Mercado del Sistema Financiero para incorporar disposiciones y establecer precisiones que permitan el desarrollo de la oferta de productos y servicios financieros en un entorno digital.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/modificacion-del-reglamento-gestion-conducta-mercado\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Modificaci\u00f3n del reglamento de gesti\u00f3n de conducta de mercado\" \/>\n<meta property=\"og:description\" content=\"La Resoluci\u00f3n SBS N\u00b0 3966-2018 modifica entre otros el Reglamento de Gesti\u00f3n de Conducta de Mercado del Sistema Financiero para incorporar disposiciones y establecer precisiones que permitan el desarrollo de la oferta de productos y servicios financieros en un entorno digital.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/modificacion-del-reglamento-gestion-conducta-mercado\/\" \/>\n<meta property=\"og:site_name\" content=\"Progreso\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fundacionmicrofinanzasbbva\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-07T12:50:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/uploads\/2018\/11\/peru-conducta-mercados.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"karessa Ramos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FMBBVA\" \/>\n<meta name=\"twitter:site\" content=\"@FMBBVA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"karessa Ramos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/modificacion-del-reglamento-gestion-conducta-mercado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/modificacion-del-reglamento-gestion-conducta-mercado\\\/\"},\"author\":{\"name\":\"karessa Ramos\",\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#\\\/schema\\\/person\\\/4a3fe64f7988998aa5e22913c8147baf\"},\"headline\":\"Modificaci\u00f3n del reglamento de gesti\u00f3n de conducta de mercado\",\"datePublished\":\"2018-12-07T12:50:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/modificacion-del-reglamento-gestion-conducta-mercado\\\/\"},\"wordCount\":351,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/modificacion-del-reglamento-gestion-conducta-mercado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/peru-conducta-mercados.jpg\",\"keywords\":[\"#comunicaci\u00f3n\",\"#reglamento\",\"Canales\",\"cl\u00e1usulas generales\",\"clientes\",\"conducta de mercado\",\"contratos\",\"digital\",\"entorno digital\",\"mecanismos de seguridad\",\"mercado\",\"Per\u00fa\",\"reporte regulatorio\",\"resoluci\u00f3n\",\"SBS\",\"seguridad\",\"sistema financiero\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/modificacion-del-reglamento-gestion-conducta-mercado\\\/\",\"url\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/modificacion-del-reglamento-gestion-conducta-mercado\\\/\",\"name\":\"Modificaci\u00f3n del reglamento de gesti\u00f3n de conducta de mercado\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/modificacion-del-reglamento-gestion-conducta-mercado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/modificacion-del-reglamento-gestion-conducta-mercado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/peru-conducta-mercados.jpg\",\"datePublished\":\"2018-12-07T12:50:23+00:00\",\"description\":\"La Resoluci\u00f3n SBS N\u00b0 3966-2018 modifica entre otros el Reglamento de Gesti\u00f3n de Conducta de Mercado del Sistema Financiero para incorporar disposiciones y establecer precisiones que permitan el desarrollo de la oferta de productos y servicios financieros en un entorno digital.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/modificacion-del-reglamento-gestion-conducta-mercado\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/modificacion-del-reglamento-gestion-conducta-mercado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/modificacion-del-reglamento-gestion-conducta-mercado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/peru-conducta-mercados.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/peru-conducta-mercados.jpg\",\"width\":400,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/modificacion-del-reglamento-gestion-conducta-mercado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Modificaci\u00f3n del reglamento de gesti\u00f3n de conducta de mercado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#website\",\"url\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/\",\"name\":\"Revista Progreso\",\"description\":\"Revista de Actualidad Jur\u00eddica\",\"publisher\":{\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#organization\"},\"alternateName\":\"Revista Progreso\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#organization\",\"name\":\"Revista Progreso\",\"alternateName\":\"Revista Progreso\",\"url\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Logo-FMBBVA-AZUL.png\",\"contentUrl\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Logo-FMBBVA-AZUL.png\",\"width\":6173,\"height\":1001,\"caption\":\"Revista Progreso\"},\"image\":{\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fundacionmicrofinanzasbbva\",\"https:\\\/\\\/x.com\\\/FMBBVA\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacin-microfinanzas-bbva\\\/\",\"https:\\\/\\\/www.instagram.com\\\/somosfmbbva\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#\\\/schema\\\/person\\\/4a3fe64f7988998aa5e22913c8147baf\",\"name\":\"karessa Ramos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2388109b4325a6fb9c892c3212e430cdc0835c8fc1c1a41f4cc2a3b175b81c5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2388109b4325a6fb9c892c3212e430cdc0835c8fc1c1a41f4cc2a3b175b81c5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2388109b4325a6fb9c892c3212e430cdc0835c8fc1c1a41f4cc2a3b175b81c5?s=96&d=mm&r=g\",\"caption\":\"karessa Ramos\"},\"url\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/author\\\/karessa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Modificaci\u00f3n del reglamento de gesti\u00f3n de conducta de mercado","description":"La Resoluci\u00f3n SBS N\u00b0 3966-2018 modifica entre otros el Reglamento de Gesti\u00f3n de Conducta de Mercado del Sistema Financiero para incorporar disposiciones y establecer precisiones que permitan el desarrollo de la oferta de productos y servicios financieros en un entorno digital.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/modificacion-del-reglamento-gestion-conducta-mercado\/","og_locale":"es_ES","og_type":"article","og_title":"Modificaci\u00f3n del reglamento de gesti\u00f3n de conducta de mercado","og_description":"La Resoluci\u00f3n SBS N\u00b0 3966-2018 modifica entre otros el Reglamento de Gesti\u00f3n de Conducta de Mercado del Sistema Financiero para incorporar disposiciones y establecer precisiones que permitan el desarrollo de la oferta de productos y servicios financieros en un entorno digital.","og_url":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/modificacion-del-reglamento-gestion-conducta-mercado\/","og_site_name":"Progreso","article_publisher":"https:\/\/www.facebook.com\/fundacionmicrofinanzasbbva","article_published_time":"2018-12-07T12:50:23+00:00","og_image":[{"width":400,"height":300,"url":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/uploads\/2018\/11\/peru-conducta-mercados.jpg","type":"image\/jpeg"}],"author":"karessa Ramos","twitter_card":"summary_large_image","twitter_creator":"@FMBBVA","twitter_site":"@FMBBVA","twitter_misc":{"Escrito por":"karessa Ramos","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/modificacion-del-reglamento-gestion-conducta-mercado\/#article","isPartOf":{"@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/modificacion-del-reglamento-gestion-conducta-mercado\/"},"author":{"name":"karessa Ramos","@id":"https:\/\/34.249.117.129\/revistaprogreso\/#\/schema\/person\/4a3fe64f7988998aa5e22913c8147baf"},"headline":"Modificaci\u00f3n del reglamento de gesti\u00f3n de conducta de mercado","datePublished":"2018-12-07T12:50:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/modificacion-del-reglamento-gestion-conducta-mercado\/"},"wordCount":351,"commentCount":0,"publisher":{"@id":"https:\/\/34.249.117.129\/revistaprogreso\/#organization"},"image":{"@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/modificacion-del-reglamento-gestion-conducta-mercado\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/uploads\/2018\/11\/peru-conducta-mercados.jpg","keywords":["#comunicaci\u00f3n","#reglamento","Canales","cl\u00e1usulas generales","clientes","conducta de mercado","contratos","digital","entorno digital","mecanismos de seguridad","mercado","Per\u00fa","reporte regulatorio","resoluci\u00f3n","SBS","seguridad","sistema financiero"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/modificacion-del-reglamento-gestion-conducta-mercado\/","url":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/modificacion-del-reglamento-gestion-conducta-mercado\/","name":"Modificaci\u00f3n del reglamento de gesti\u00f3n de conducta de mercado","isPartOf":{"@id":"https:\/\/34.249.117.129\/revistaprogreso\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/modificacion-del-reglamento-gestion-conducta-mercado\/#primaryimage"},"image":{"@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/modificacion-del-reglamento-gestion-conducta-mercado\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/uploads\/2018\/11\/peru-conducta-mercados.jpg","datePublished":"2018-12-07T12:50:23+00:00","description":"La Resoluci\u00f3n SBS N\u00b0 3966-2018 modifica entre otros el Reglamento de Gesti\u00f3n de Conducta de Mercado del Sistema Financiero para incorporar disposiciones y establecer precisiones que permitan el desarrollo de la oferta de productos y servicios financieros en un entorno digital.","breadcrumb":{"@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/modificacion-del-reglamento-gestion-conducta-mercado\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/modificacion-del-reglamento-gestion-conducta-mercado\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/modificacion-del-reglamento-gestion-conducta-mercado\/#primaryimage","url":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/uploads\/2018\/11\/peru-conducta-mercados.jpg","contentUrl":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/uploads\/2018\/11\/peru-conducta-mercados.jpg","width":400,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/modificacion-del-reglamento-gestion-conducta-mercado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/34.249.117.129\/revistaprogreso\/"},{"@type":"ListItem","position":2,"name":"Modificaci\u00f3n del reglamento de gesti\u00f3n de conducta de mercado"}]},{"@type":"WebSite","@id":"https:\/\/34.249.117.129\/revistaprogreso\/#website","url":"https:\/\/34.249.117.129\/revistaprogreso\/","name":"Revista Progreso","description":"Revista de Actualidad Jur\u00eddica","publisher":{"@id":"https:\/\/34.249.117.129\/revistaprogreso\/#organization"},"alternateName":"Revista Progreso","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/34.249.117.129\/revistaprogreso\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/34.249.117.129\/revistaprogreso\/#organization","name":"Revista Progreso","alternateName":"Revista Progreso","url":"https:\/\/34.249.117.129\/revistaprogreso\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/34.249.117.129\/revistaprogreso\/#\/schema\/logo\/image\/","url":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/uploads\/2023\/09\/Logo-FMBBVA-AZUL.png","contentUrl":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/uploads\/2023\/09\/Logo-FMBBVA-AZUL.png","width":6173,"height":1001,"caption":"Revista Progreso"},"image":{"@id":"https:\/\/34.249.117.129\/revistaprogreso\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fundacionmicrofinanzasbbva","https:\/\/x.com\/FMBBVA","https:\/\/www.linkedin.com\/company\/fundacin-microfinanzas-bbva\/","https:\/\/www.instagram.com\/somosfmbbva\/"]},{"@type":"Person","@id":"https:\/\/34.249.117.129\/revistaprogreso\/#\/schema\/person\/4a3fe64f7988998aa5e22913c8147baf","name":"karessa Ramos","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a2388109b4325a6fb9c892c3212e430cdc0835c8fc1c1a41f4cc2a3b175b81c5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a2388109b4325a6fb9c892c3212e430cdc0835c8fc1c1a41f4cc2a3b175b81c5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2388109b4325a6fb9c892c3212e430cdc0835c8fc1c1a41f4cc2a3b175b81c5?s=96&d=mm&r=g","caption":"karessa Ramos"},"url":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/author\/karessa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/posts\/12815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/comments?post=12815"}],"version-history":[{"count":0,"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/posts\/12815\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/media\/12817"}],"wp:attachment":[{"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/media?parent=12815"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/tags?post=12815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}