{"id":12479,"date":"2018-09-17T11:56:07","date_gmt":"2018-09-17T11:56:07","guid":{"rendered":"http:\/\/progresomicrofinanzas.org\/?p=12479\/"},"modified":"2018-09-17T11:56:07","modified_gmt":"2018-09-17T11:56:07","slug":"modificacion-del-reglamento-microcredito","status":"publish","type":"post","link":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/modificacion-del-reglamento-microcredito\/","title":{"rendered":"Modificaci\u00f3n del Reglamento de Microcr\u00e9dito"},"content":{"rendered":"<div class=\"pdfprnt-buttons pdfprnt-buttons-post pdfprnt-top-right\"><a href=\"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/posts\/12479?print=pdf\" class=\"pdfprnt-button pdfprnt-button-pdf\" target=\"_blank\" ><img decoding=\"async\" src=\"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/plugins\/pdf-print\/images\/pdf.png\" alt=\"image_pdf\" title=\"Ver PDF\" \/><\/a><a href=\"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/posts\/12479?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\" ><img decoding=\"async\" src=\"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/plugins\/pdf-print\/images\/print.png\" alt=\"image_print\" title=\"Imprimir contenido\" \/><\/a><\/div><p><span style=\"font-weight: 400;\">El pasado 9 de julio la Superintendencia de Bancos hizo p\u00fablica la aprobaci\u00f3n del nuevo Reglamento de Microcr\u00e9dito de la Junta Monetaria de la Rep\u00fablica Dominicana del 17 de mayo de 2018, mediante su Primera Resoluci\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La norma, que modifica integralmente el Reglamento de Microcr\u00e9ditos de 2014, pretende actualizar el marco normativo para homogeneizarlo a las nuevas disposiciones del Reglamento de Evaluaci\u00f3n de Activos (REA)*. En este sentido, los aspectos relativos al otorgamiento, evaluaci\u00f3n y gesti\u00f3n de los microcr\u00e9ditos, se homogeneizar\u00e1n para evitar distorsiones no justificadas en las metodolog\u00edas de medici\u00f3n de riesgo de cr\u00e9dito, pero conservando elementos diferenciadores para abordar aspectos distintivos del ciclo de vida del microcr\u00e9dito as\u00ed como sus modalidades.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Entre las novedades previstas por el Reglamento de Microcr\u00e9ditos destacan las siguientes:<\/span><\/p>\n<p><b>Definiciones<\/b><span style=\"font-weight: 400;\">:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">-Inclusi\u00f3n de las unidades formales en la definici\u00f3n de \u2018<\/span><i><span style=\"font-weight: 400;\">actividad o negocio en peque\u00f1a escala\u2019<\/span><\/i><span style=\"font-weight: 400;\">, con el fin de incluir a las microempresas que se encuentran formalizadas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">-Sustituci\u00f3n, en la definici\u00f3n de microcr\u00e9dito, de \u2018<\/span><i><span style=\"font-weight: 400;\">ventas anuales inferiores a RD$8,000,000.00\u2019<\/span><\/i><span style=\"font-weight: 400;\">, por \u2018<\/span><i><span style=\"font-weight: 400;\">deudas consolidadas en el sistema financiero que no superen los 50 salarios m\u00ednimos<\/span><\/i><span style=\"font-weight: 400;\">\u2019; ya que el Reglamento establece las caracter\u00edsticas del producto microcr\u00e9dito y no del tipo de cliente, al no especificar que sea una microempresa.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">-Se modifica la definici\u00f3n de Refinanciaci\u00f3n, para reducir la importancia de los pr\u00e9stamos de consolidaci\u00f3n de deuda, tomando en cuenta que puede representar una proporci\u00f3n peque\u00f1a del nuevo cr\u00e9dito y puede no ser el motivo principal de la nueva solicitud. El \u00f3rgano regulador otorga mayor importancia a que las entidades de intermediaci\u00f3n financiera (EIF), cobren oportunamente los cr\u00e9ditos dentro del plazo establecido, con especial \u00e9nfasis en los casos en que se pague primero el inter\u00e9s que el capital.<\/span><\/p>\n<p><b>Extensi\u00f3n del plazo<\/b><\/p>\n<p><span style=\"font-weight: 400;\">El Reglamento introduce aspectos novedosos en cuanto a las caracter\u00edsticas necesarias para calificar a una operaci\u00f3n crediticia como microcr\u00e9dito. Entre ellas, extiende el plazo del cr\u00e9dito de 24 a 36 meses, y en el caso de las inversiones fijas, de 60 a 72 meses para una mayor consistencia con el REA y permitir una mayor flexibilidad en los planes de pago, considerando el incremento del monto que sirve como punto de corte, equivalente a 50 salarios m\u00ednimos.<\/span><\/p>\n<p><b>Otros aspectos relevantes<\/b><\/p>\n<p><span style=\"font-weight: 400;\">La norma modificada incorpora una serie de documentos que deben aportar los microempresarios para acceder a los cr\u00e9ditos, que los fuerza a estar debidamente formalizados y organizados de manera contable, al tiempo que las EIF deben realizar cambios en sus plataformas de archivos f\u00edsicos, tecnol\u00f3gicos, entre otras actualizaciones.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El regulador ha dispuesto tambi\u00e9n que, para las evaluaciones de los clientes de microcr\u00e9dito, sus deudas por EIF deben ser consolidadas. No obstante, otra EIF que intente ponderar a un potencial cliente, no podr\u00e1 visualizar su calificaci\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La Ley N\u00b0. 155-17 del 31 de mayo de 2017, sobre Lavado de activos y financiamiento del\u00a0<\/span><span style=\"font-weight: 400;\">terrorismo, fue tomada en cuenta para esta nueva versi\u00f3n de Reglamento de Microcr\u00e9ditos, debido a la importancia de la documentaci\u00f3n requerida por esta pieza legal en el proceso de la Debida Diligencia que deben realizar las EIF.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La actualizaci\u00f3n del Reglamento de Microcr\u00e9ditos constituye un instrumento positivo para el microempresario, pues con las obligaciones de formalizaci\u00f3n integral se fomenta el crecimiento empresarial, al tiempo que el Estado tiene una mayor claridad del crecimiento econ\u00f3mico por sector microempresarial.<\/span><\/p>\n<div class=\"note\">\n<p><span style=\"font-weight: 400;\">*Aprobado mediante la Segunda Resoluci\u00f3n de la Junta Monetaria de 28 de septiembre del 2017 y que entr\u00f3 en vigor el 2 de enero de 2018<\/span><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El pasado 9 de julio la Superintendencia de Bancos hizo p\u00fablica la aprobaci\u00f3n del nuevo Reglamento de Microcr\u00e9dito de la Junta Monetaria de la Rep\u00fablica Dominicana del 17 de mayo de 2018, mediante su Primera Resoluci\u00f3n. La norma, que modifica integralmente el Reglamento de Microcr\u00e9ditos de 2014, pretende actualizar el marco normativo para homogeneizarlo a [&hellip;]<\/p>\n","protected":false},"author":30,"featured_media":12482,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"tags":[179,175,3658,3660,3659,3655,3656,3657,3661,243,3654],"class_list":["post-12479","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-reglamento","tag-riesgos","tag-cartera-de-credito","tag-eif","tag-entidad-de-intermediacion-financiera","tag-entidad-financiera","tag-garantias-consolidacion-de-deuda","tag-grupo-solidario","tag-lavado-de-activos-y-financiamiento-del-terrorismo","tag-microcredito","tag-refinanciacion","numero-16m","seccion-legislacion-normas-publicadas-microfinanzas","pais-republica-dominicana"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Modificaci\u00f3n del Reglamento de Microcr\u00e9dito<\/title>\n<meta name=\"description\" content=\"Aprobaci\u00f3n del nuevo Reglamento de Microcr\u00e9dito por la Junta Monetaria de la Rep\u00fablica Dominicana\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/modificacion-del-reglamento-microcredito\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Modificaci\u00f3n del Reglamento de Microcr\u00e9dito\" \/>\n<meta property=\"og:description\" content=\"Aprobaci\u00f3n del nuevo Reglamento de Microcr\u00e9dito por la Junta Monetaria de la Rep\u00fablica Dominicana\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/modificacion-del-reglamento-microcredito\/\" \/>\n<meta property=\"og:site_name\" content=\"Progreso\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fundacionmicrofinanzasbbva\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-17T11:56:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/uploads\/2018\/09\/shutterstock_34989229.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"648\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"karessa Ramos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FMBBVA\" \/>\n<meta name=\"twitter:site\" content=\"@FMBBVA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"karessa Ramos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/modificacion-del-reglamento-microcredito\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/modificacion-del-reglamento-microcredito\\\/\"},\"author\":{\"name\":\"karessa Ramos\",\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#\\\/schema\\\/person\\\/4a3fe64f7988998aa5e22913c8147baf\"},\"headline\":\"Modificaci\u00f3n del Reglamento de Microcr\u00e9dito\",\"datePublished\":\"2018-09-17T11:56:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/modificacion-del-reglamento-microcredito\\\/\"},\"wordCount\":614,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/modificacion-del-reglamento-microcredito\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/shutterstock_34989229.jpg\",\"keywords\":[\"#reglamento\",\"#riesgos\",\"cartera de cr\u00e9dito\",\"EIF\",\"entidad de intermediaci\u00f3n financiera\",\"entidad financiera\",\"garant\u00edas consolidaci\u00f3n de deuda\",\"grupo solidario\",\"Lavado de activos y financiamiento del terrorismo\",\"microcr\u00e9dito\",\"refinanciaci\u00f3n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/modificacion-del-reglamento-microcredito\\\/\",\"url\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/modificacion-del-reglamento-microcredito\\\/\",\"name\":\"Modificaci\u00f3n del Reglamento de Microcr\u00e9dito\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/modificacion-del-reglamento-microcredito\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/modificacion-del-reglamento-microcredito\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/shutterstock_34989229.jpg\",\"datePublished\":\"2018-09-17T11:56:07+00:00\",\"description\":\"Aprobaci\u00f3n del nuevo Reglamento de Microcr\u00e9dito por la Junta Monetaria de la Rep\u00fablica Dominicana\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/modificacion-del-reglamento-microcredito\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/modificacion-del-reglamento-microcredito\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/modificacion-del-reglamento-microcredito\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/shutterstock_34989229.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/shutterstock_34989229.jpg\",\"width\":1000,\"height\":648},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/modificacion-del-reglamento-microcredito\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Modificaci\u00f3n del Reglamento de Microcr\u00e9dito\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#website\",\"url\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/\",\"name\":\"Revista Progreso\",\"description\":\"Revista de Actualidad Jur\u00eddica\",\"publisher\":{\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#organization\"},\"alternateName\":\"Revista Progreso\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#organization\",\"name\":\"Revista Progreso\",\"alternateName\":\"Revista Progreso\",\"url\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Logo-FMBBVA-AZUL.png\",\"contentUrl\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Logo-FMBBVA-AZUL.png\",\"width\":6173,\"height\":1001,\"caption\":\"Revista Progreso\"},\"image\":{\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fundacionmicrofinanzasbbva\",\"https:\\\/\\\/x.com\\\/FMBBVA\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacin-microfinanzas-bbva\\\/\",\"https:\\\/\\\/www.instagram.com\\\/somosfmbbva\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#\\\/schema\\\/person\\\/4a3fe64f7988998aa5e22913c8147baf\",\"name\":\"karessa Ramos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2388109b4325a6fb9c892c3212e430cdc0835c8fc1c1a41f4cc2a3b175b81c5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2388109b4325a6fb9c892c3212e430cdc0835c8fc1c1a41f4cc2a3b175b81c5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2388109b4325a6fb9c892c3212e430cdc0835c8fc1c1a41f4cc2a3b175b81c5?s=96&d=mm&r=g\",\"caption\":\"karessa Ramos\"},\"url\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/author\\\/karessa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Modificaci\u00f3n del Reglamento de Microcr\u00e9dito","description":"Aprobaci\u00f3n del nuevo Reglamento de Microcr\u00e9dito por la Junta Monetaria de la Rep\u00fablica Dominicana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/modificacion-del-reglamento-microcredito\/","og_locale":"es_ES","og_type":"article","og_title":"Modificaci\u00f3n del Reglamento de Microcr\u00e9dito","og_description":"Aprobaci\u00f3n del nuevo Reglamento de Microcr\u00e9dito por la Junta Monetaria de la Rep\u00fablica Dominicana","og_url":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/modificacion-del-reglamento-microcredito\/","og_site_name":"Progreso","article_publisher":"https:\/\/www.facebook.com\/fundacionmicrofinanzasbbva","article_published_time":"2018-09-17T11:56:07+00:00","og_image":[{"width":1000,"height":648,"url":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/uploads\/2018\/09\/shutterstock_34989229.jpg","type":"image\/jpeg"}],"author":"karessa Ramos","twitter_card":"summary_large_image","twitter_creator":"@FMBBVA","twitter_site":"@FMBBVA","twitter_misc":{"Escrito por":"karessa Ramos","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/modificacion-del-reglamento-microcredito\/#article","isPartOf":{"@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/modificacion-del-reglamento-microcredito\/"},"author":{"name":"karessa Ramos","@id":"https:\/\/34.249.117.129\/revistaprogreso\/#\/schema\/person\/4a3fe64f7988998aa5e22913c8147baf"},"headline":"Modificaci\u00f3n del Reglamento de Microcr\u00e9dito","datePublished":"2018-09-17T11:56:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/modificacion-del-reglamento-microcredito\/"},"wordCount":614,"commentCount":0,"publisher":{"@id":"https:\/\/34.249.117.129\/revistaprogreso\/#organization"},"image":{"@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/modificacion-del-reglamento-microcredito\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/uploads\/2018\/09\/shutterstock_34989229.jpg","keywords":["#reglamento","#riesgos","cartera de cr\u00e9dito","EIF","entidad de intermediaci\u00f3n financiera","entidad financiera","garant\u00edas consolidaci\u00f3n de deuda","grupo solidario","Lavado de activos y financiamiento del terrorismo","microcr\u00e9dito","refinanciaci\u00f3n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/modificacion-del-reglamento-microcredito\/","url":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/modificacion-del-reglamento-microcredito\/","name":"Modificaci\u00f3n del Reglamento de Microcr\u00e9dito","isPartOf":{"@id":"https:\/\/34.249.117.129\/revistaprogreso\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/modificacion-del-reglamento-microcredito\/#primaryimage"},"image":{"@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/modificacion-del-reglamento-microcredito\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/uploads\/2018\/09\/shutterstock_34989229.jpg","datePublished":"2018-09-17T11:56:07+00:00","description":"Aprobaci\u00f3n del nuevo Reglamento de Microcr\u00e9dito por la Junta Monetaria de la Rep\u00fablica Dominicana","breadcrumb":{"@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/modificacion-del-reglamento-microcredito\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/modificacion-del-reglamento-microcredito\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/modificacion-del-reglamento-microcredito\/#primaryimage","url":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/uploads\/2018\/09\/shutterstock_34989229.jpg","contentUrl":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/uploads\/2018\/09\/shutterstock_34989229.jpg","width":1000,"height":648},{"@type":"BreadcrumbList","@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/modificacion-del-reglamento-microcredito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/34.249.117.129\/revistaprogreso\/"},{"@type":"ListItem","position":2,"name":"Modificaci\u00f3n del Reglamento de Microcr\u00e9dito"}]},{"@type":"WebSite","@id":"https:\/\/34.249.117.129\/revistaprogreso\/#website","url":"https:\/\/34.249.117.129\/revistaprogreso\/","name":"Revista Progreso","description":"Revista de Actualidad Jur\u00eddica","publisher":{"@id":"https:\/\/34.249.117.129\/revistaprogreso\/#organization"},"alternateName":"Revista Progreso","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/34.249.117.129\/revistaprogreso\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/34.249.117.129\/revistaprogreso\/#organization","name":"Revista Progreso","alternateName":"Revista Progreso","url":"https:\/\/34.249.117.129\/revistaprogreso\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/34.249.117.129\/revistaprogreso\/#\/schema\/logo\/image\/","url":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/uploads\/2023\/09\/Logo-FMBBVA-AZUL.png","contentUrl":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/uploads\/2023\/09\/Logo-FMBBVA-AZUL.png","width":6173,"height":1001,"caption":"Revista Progreso"},"image":{"@id":"https:\/\/34.249.117.129\/revistaprogreso\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fundacionmicrofinanzasbbva","https:\/\/x.com\/FMBBVA","https:\/\/www.linkedin.com\/company\/fundacin-microfinanzas-bbva\/","https:\/\/www.instagram.com\/somosfmbbva\/"]},{"@type":"Person","@id":"https:\/\/34.249.117.129\/revistaprogreso\/#\/schema\/person\/4a3fe64f7988998aa5e22913c8147baf","name":"karessa Ramos","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a2388109b4325a6fb9c892c3212e430cdc0835c8fc1c1a41f4cc2a3b175b81c5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a2388109b4325a6fb9c892c3212e430cdc0835c8fc1c1a41f4cc2a3b175b81c5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2388109b4325a6fb9c892c3212e430cdc0835c8fc1c1a41f4cc2a3b175b81c5?s=96&d=mm&r=g","caption":"karessa Ramos"},"url":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/author\/karessa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/posts\/12479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/comments?post=12479"}],"version-history":[{"count":0,"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/posts\/12479\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/media\/12482"}],"wp:attachment":[{"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/media?parent=12479"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/tags?post=12479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}