{"id":11469,"date":"2018-06-25T14:22:56","date_gmt":"2018-06-25T14:22:56","guid":{"rendered":"http:\/\/progresomicrofinanzas.org\/?p=11469\/"},"modified":"2018-09-11T10:43:54","modified_gmt":"2018-09-11T10:43:54","slug":"actualizacion-obligaciones-companias-aseguradoras-seguro-agropecuario","status":"publish","type":"post","link":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/actualizacion-obligaciones-companias-aseguradoras-seguro-agropecuario\/","title":{"rendered":"Actualizaci\u00f3n de obligaciones de compa\u00f1\u00edas aseguradoras"},"content":{"rendered":"<div class=\"pdfprnt-buttons pdfprnt-buttons-post pdfprnt-top-right\"><a href=\"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/posts\/11469?print=pdf\" class=\"pdfprnt-button pdfprnt-button-pdf\" target=\"_blank\" ><img decoding=\"async\" src=\"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/plugins\/pdf-print\/images\/pdf.png\" alt=\"image_pdf\" title=\"Ver PDF\" \/><\/a><a href=\"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/posts\/11469?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\" ><img decoding=\"async\" src=\"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/plugins\/pdf-print\/images\/print.png\" alt=\"image_print\" title=\"Imprimir contenido\" \/><\/a><\/div><p><span style=\"font-weight: 400;\">El Gobierno colombiano entiende legalmente el seguro agropecuario como un instrumento para proteger e incentivar la producci\u00f3n de alimentos, buscar el mejoramiento econ\u00f3mico del sector rural y proteger las inversiones. As\u00ed, el Estado participa en el pago de las primas que los productores agropecuarios deban sufragar para tomar este seguro agropecuario.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para este prop\u00f3sito se ampli\u00f3 el objeto del Fondo Nacional de Riesgos Agropecuarios, administrado por el Fondo para el Financiamiento del Sector Agropecuario (FINAGRO), con el objetivo de cofinanciar los costos para el fortalecimiento t\u00e9cnico del seguro agropecuario y de fomentar la gesti\u00f3n de riesgos en el sector, adem\u00e1s del otorgamiento de subsidios, apoyos o incentivos para implementar instrumentos de gesti\u00f3n de riesgos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En el marco de este fortalecimiento y de acuerdo con la reglamentaci\u00f3n emitida, con esta Circular de FINAGRO se han actualizado algunos aspectos del seguro agropecuario relacionados con las obligaciones de las compa\u00f1\u00edas aseguradoras, entre las cuales se destacan las siguientes: <\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Cronograma para el reporte de siniestros por parte de las compa\u00f1\u00edas aseguradoras: para siniestros atendidos en el primer semestre del a\u00f1o 2018, la fecha l\u00edmite de reporte ser\u00e1 en agosto de 2018; y para aquellos atendidos durante el segundo semestre, la fecha l\u00edmite ser\u00e1 en febrero de 2019.<\/span><\/li>\n<\/ul>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Actualizaci\u00f3n del esquema de distribuci\u00f3n del Incentivo al Seguro Agropecuario.<\/span><\/li>\n<\/ul>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Inclusi\u00f3n del Anexo denominado \u201cCertificaci\u00f3n de adopci\u00f3n de mecanismos de prevenci\u00f3n y control de lavado de activos y financiamiento del terrorismo para Instituciones Financieras\u201d.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Adem\u00e1s, se actualizan las fechas de pago por parte de las compa\u00f1\u00edas aseguradoras al Fondo Nacional de Riesgos Agropecuarios del 1% sobre el valor de las primas, el marco normativo del seguro agropecuario y la actualizaci\u00f3n del anexo denominado \u201c<\/span><i><span style=\"font-weight: 400;\">Declaraci\u00f3n del Tipo de Productor<\/span><\/i><span style=\"font-weight: 400;\">\u201d, que debe ser diligenciado por las compa\u00f1\u00edas aseguradoras.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno colombiano entiende legalmente el seguro agropecuario como un instrumento para proteger e incentivar la producci\u00f3n de alimentos, buscar el mejoramiento econ\u00f3mico del sector rural y proteger las inversiones. As\u00ed, el Estado participa en el pago de las primas que los productores agropecuarios deban sufragar para tomar este seguro agropecuario. Para este prop\u00f3sito se [&hellip;]<\/p>\n","protected":false},"author":30,"featured_media":11474,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"tags":[93,245,208,246,2201,3186,3181,3182,3183,3185,3184,313,1219],"class_list":["post-11469","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-aseguradoras","tag-agropecuario","tag-colombia","tag-finagro","tag-financiamiento-del-terrorismo","tag-fondo-nacional-de-riesgos-agropecuarios","tag-incentivo","tag-incentivo-al-seguro-agropecuario","tag-isa","tag-lado-de-activos","tag-riesgo-agropecuario","tag-sector-agropecuario","tag-seguro-agropecuario","numero-15m","seccion-legislacion-normas-publicadas-microfinanzas","pais-colombia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Actualizaci\u00f3n de obligaciones de compa\u00f1\u00edas aseguradoras<\/title>\n<meta name=\"description\" content=\"El Gobierno colombiano actualiza disposiciones acerca de las obligaciones por parte de las compa\u00f1\u00edas aseguradoras, para acceder al Incentivo al Seguro Agropecuario \u2013 ISA.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/actualizacion-obligaciones-companias-aseguradoras-seguro-agropecuario\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Actualizaci\u00f3n de obligaciones de compa\u00f1\u00edas aseguradoras\" \/>\n<meta property=\"og:description\" content=\"El Gobierno colombiano actualiza disposiciones acerca de las obligaciones por parte de las compa\u00f1\u00edas aseguradoras, para acceder al Incentivo al Seguro Agropecuario \u2013 ISA.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/actualizacion-obligaciones-companias-aseguradoras-seguro-agropecuario\/\" \/>\n<meta property=\"og:site_name\" content=\"Progreso\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fundacionmicrofinanzasbbva\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-25T14:22:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-11T10:43:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/uploads\/2018\/05\/Col-seguro-agro.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"karessa Ramos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FMBBVA\" \/>\n<meta name=\"twitter:site\" content=\"@FMBBVA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"karessa Ramos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/actualizacion-obligaciones-companias-aseguradoras-seguro-agropecuario\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/actualizacion-obligaciones-companias-aseguradoras-seguro-agropecuario\\\/\"},\"author\":{\"name\":\"karessa Ramos\",\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#\\\/schema\\\/person\\\/4a3fe64f7988998aa5e22913c8147baf\"},\"headline\":\"Actualizaci\u00f3n de obligaciones de compa\u00f1\u00edas aseguradoras\",\"datePublished\":\"2018-06-25T14:22:56+00:00\",\"dateModified\":\"2018-09-11T10:43:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/actualizacion-obligaciones-companias-aseguradoras-seguro-agropecuario\\\/\"},\"wordCount\":317,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/actualizacion-obligaciones-companias-aseguradoras-seguro-agropecuario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Col-seguro-agro.jpg\",\"keywords\":[\"#aseguradoras\",\"agropecuario\",\"Colombia\",\"FINAGRO\",\"financiamiento del Terrorismo\",\"Fondo Nacional de Riesgos Agropecuarios\",\"incentivo\",\"Incentivo al Seguro Agropecuario\",\"ISA\",\"lado de activos\",\"riesgo agropecuario\",\"sector agropecuario\",\"seguro \u00a0agropecuario\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/actualizacion-obligaciones-companias-aseguradoras-seguro-agropecuario\\\/\",\"url\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/actualizacion-obligaciones-companias-aseguradoras-seguro-agropecuario\\\/\",\"name\":\"Actualizaci\u00f3n de obligaciones de compa\u00f1\u00edas aseguradoras\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/actualizacion-obligaciones-companias-aseguradoras-seguro-agropecuario\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/actualizacion-obligaciones-companias-aseguradoras-seguro-agropecuario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Col-seguro-agro.jpg\",\"datePublished\":\"2018-06-25T14:22:56+00:00\",\"dateModified\":\"2018-09-11T10:43:54+00:00\",\"description\":\"El Gobierno colombiano actualiza disposiciones acerca de las obligaciones por parte de las compa\u00f1\u00edas aseguradoras, para acceder al Incentivo al Seguro Agropecuario \u2013 ISA.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/actualizacion-obligaciones-companias-aseguradoras-seguro-agropecuario\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/actualizacion-obligaciones-companias-aseguradoras-seguro-agropecuario\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/actualizacion-obligaciones-companias-aseguradoras-seguro-agropecuario\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Col-seguro-agro.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Col-seguro-agro.jpg\",\"width\":400,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/actualizacion-obligaciones-companias-aseguradoras-seguro-agropecuario\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actualizaci\u00f3n de obligaciones de compa\u00f1\u00edas aseguradoras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#website\",\"url\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/\",\"name\":\"Revista Progreso\",\"description\":\"Revista de Actualidad Jur\u00eddica\",\"publisher\":{\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#organization\"},\"alternateName\":\"Revista Progreso\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#organization\",\"name\":\"Revista Progreso\",\"alternateName\":\"Revista Progreso\",\"url\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Logo-FMBBVA-AZUL.png\",\"contentUrl\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Logo-FMBBVA-AZUL.png\",\"width\":6173,\"height\":1001,\"caption\":\"Revista Progreso\"},\"image\":{\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fundacionmicrofinanzasbbva\",\"https:\\\/\\\/x.com\\\/FMBBVA\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacin-microfinanzas-bbva\\\/\",\"https:\\\/\\\/www.instagram.com\\\/somosfmbbva\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/34.249.117.129\\\/revistaprogreso\\\/#\\\/schema\\\/person\\\/4a3fe64f7988998aa5e22913c8147baf\",\"name\":\"karessa Ramos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2388109b4325a6fb9c892c3212e430cdc0835c8fc1c1a41f4cc2a3b175b81c5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2388109b4325a6fb9c892c3212e430cdc0835c8fc1c1a41f4cc2a3b175b81c5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2388109b4325a6fb9c892c3212e430cdc0835c8fc1c1a41f4cc2a3b175b81c5?s=96&d=mm&r=g\",\"caption\":\"karessa Ramos\"},\"url\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/revistaprogreso\\\/author\\\/karessa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Actualizaci\u00f3n de obligaciones de compa\u00f1\u00edas aseguradoras","description":"El Gobierno colombiano actualiza disposiciones acerca de las obligaciones por parte de las compa\u00f1\u00edas aseguradoras, para acceder al Incentivo al Seguro Agropecuario \u2013 ISA.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/actualizacion-obligaciones-companias-aseguradoras-seguro-agropecuario\/","og_locale":"es_ES","og_type":"article","og_title":"Actualizaci\u00f3n de obligaciones de compa\u00f1\u00edas aseguradoras","og_description":"El Gobierno colombiano actualiza disposiciones acerca de las obligaciones por parte de las compa\u00f1\u00edas aseguradoras, para acceder al Incentivo al Seguro Agropecuario \u2013 ISA.","og_url":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/actualizacion-obligaciones-companias-aseguradoras-seguro-agropecuario\/","og_site_name":"Progreso","article_publisher":"https:\/\/www.facebook.com\/fundacionmicrofinanzasbbva","article_published_time":"2018-06-25T14:22:56+00:00","article_modified_time":"2018-09-11T10:43:54+00:00","og_image":[{"width":400,"height":300,"url":"https:\/\/fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/uploads\/2018\/05\/Col-seguro-agro.jpg","type":"image\/jpeg"}],"author":"karessa Ramos","twitter_card":"summary_large_image","twitter_creator":"@FMBBVA","twitter_site":"@FMBBVA","twitter_misc":{"Escrito por":"karessa Ramos","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/actualizacion-obligaciones-companias-aseguradoras-seguro-agropecuario\/#article","isPartOf":{"@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/actualizacion-obligaciones-companias-aseguradoras-seguro-agropecuario\/"},"author":{"name":"karessa Ramos","@id":"https:\/\/34.249.117.129\/revistaprogreso\/#\/schema\/person\/4a3fe64f7988998aa5e22913c8147baf"},"headline":"Actualizaci\u00f3n de obligaciones de compa\u00f1\u00edas aseguradoras","datePublished":"2018-06-25T14:22:56+00:00","dateModified":"2018-09-11T10:43:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/actualizacion-obligaciones-companias-aseguradoras-seguro-agropecuario\/"},"wordCount":317,"commentCount":0,"publisher":{"@id":"https:\/\/34.249.117.129\/revistaprogreso\/#organization"},"image":{"@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/actualizacion-obligaciones-companias-aseguradoras-seguro-agropecuario\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/uploads\/2018\/05\/Col-seguro-agro.jpg","keywords":["#aseguradoras","agropecuario","Colombia","FINAGRO","financiamiento del Terrorismo","Fondo Nacional de Riesgos Agropecuarios","incentivo","Incentivo al Seguro Agropecuario","ISA","lado de activos","riesgo agropecuario","sector agropecuario","seguro \u00a0agropecuario"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/actualizacion-obligaciones-companias-aseguradoras-seguro-agropecuario\/","url":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/actualizacion-obligaciones-companias-aseguradoras-seguro-agropecuario\/","name":"Actualizaci\u00f3n de obligaciones de compa\u00f1\u00edas aseguradoras","isPartOf":{"@id":"https:\/\/34.249.117.129\/revistaprogreso\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/actualizacion-obligaciones-companias-aseguradoras-seguro-agropecuario\/#primaryimage"},"image":{"@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/actualizacion-obligaciones-companias-aseguradoras-seguro-agropecuario\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/uploads\/2018\/05\/Col-seguro-agro.jpg","datePublished":"2018-06-25T14:22:56+00:00","dateModified":"2018-09-11T10:43:54+00:00","description":"El Gobierno colombiano actualiza disposiciones acerca de las obligaciones por parte de las compa\u00f1\u00edas aseguradoras, para acceder al Incentivo al Seguro Agropecuario \u2013 ISA.","breadcrumb":{"@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/actualizacion-obligaciones-companias-aseguradoras-seguro-agropecuario\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/actualizacion-obligaciones-companias-aseguradoras-seguro-agropecuario\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/actualizacion-obligaciones-companias-aseguradoras-seguro-agropecuario\/#primaryimage","url":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/uploads\/2018\/05\/Col-seguro-agro.jpg","contentUrl":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/uploads\/2018\/05\/Col-seguro-agro.jpg","width":400,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/actualizacion-obligaciones-companias-aseguradoras-seguro-agropecuario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/34.249.117.129\/revistaprogreso\/"},{"@type":"ListItem","position":2,"name":"Actualizaci\u00f3n de obligaciones de compa\u00f1\u00edas aseguradoras"}]},{"@type":"WebSite","@id":"https:\/\/34.249.117.129\/revistaprogreso\/#website","url":"https:\/\/34.249.117.129\/revistaprogreso\/","name":"Revista Progreso","description":"Revista de Actualidad Jur\u00eddica","publisher":{"@id":"https:\/\/34.249.117.129\/revistaprogreso\/#organization"},"alternateName":"Revista Progreso","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/34.249.117.129\/revistaprogreso\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/34.249.117.129\/revistaprogreso\/#organization","name":"Revista Progreso","alternateName":"Revista Progreso","url":"https:\/\/34.249.117.129\/revistaprogreso\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/34.249.117.129\/revistaprogreso\/#\/schema\/logo\/image\/","url":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/uploads\/2023\/09\/Logo-FMBBVA-AZUL.png","contentUrl":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-content\/uploads\/2023\/09\/Logo-FMBBVA-AZUL.png","width":6173,"height":1001,"caption":"Revista Progreso"},"image":{"@id":"https:\/\/34.249.117.129\/revistaprogreso\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fundacionmicrofinanzasbbva","https:\/\/x.com\/FMBBVA","https:\/\/www.linkedin.com\/company\/fundacin-microfinanzas-bbva\/","https:\/\/www.instagram.com\/somosfmbbva\/"]},{"@type":"Person","@id":"https:\/\/34.249.117.129\/revistaprogreso\/#\/schema\/person\/4a3fe64f7988998aa5e22913c8147baf","name":"karessa Ramos","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a2388109b4325a6fb9c892c3212e430cdc0835c8fc1c1a41f4cc2a3b175b81c5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a2388109b4325a6fb9c892c3212e430cdc0835c8fc1c1a41f4cc2a3b175b81c5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2388109b4325a6fb9c892c3212e430cdc0835c8fc1c1a41f4cc2a3b175b81c5?s=96&d=mm&r=g","caption":"karessa Ramos"},"url":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/author\/karessa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/posts\/11469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/comments?post=11469"}],"version-history":[{"count":0,"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/posts\/11469\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/media\/11474"}],"wp:attachment":[{"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/media?parent=11469"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/revistaprogreso\/wp-json\/wp\/v2\/tags?post=11469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}