{"id":1292,"count":1,"description":"","link":"https:\/\/www.fundacionmicrofinanzasbbva.org\/en\/tag\/premio-madre-ejemplar-2016-en\/","name":"Premio \u201cMadre Ejemplar 2016\u201d","slug":"premio-madre-ejemplar-2016-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Premio \u201cMadre Ejemplar 2016\u201d archivos - Fundaci\u00f3n Microfinanzas BBVA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fundacionmicrofinanzasbbva.org\/en\/tag\/premio-madre-ejemplar-2016-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Premio \u201cMadre Ejemplar 2016\u201d archivos - Fundaci\u00f3n Microfinanzas BBVA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fundacionmicrofinanzasbbva.org\/en\/tag\/premio-madre-ejemplar-2016-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n Microfinanzas BBVA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fundacionmicrofinanzasbbva.org\/wp-content\/uploads\/2017\/01\/favicon.png\" \/>\n\t<meta property=\"og:image:width\" content=\"130\" \/>\n\t<meta property=\"og:image:height\" content=\"130\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@FMBBVA\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/en\\\/tag\\\/premio-madre-ejemplar-2016-en\\\/\",\"url\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/en\\\/tag\\\/premio-madre-ejemplar-2016-en\\\/\",\"name\":\"Premio \u201cMadre Ejemplar 2016\u201d archivos - Fundaci\u00f3n Microfinanzas BBVA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/en\\\/tag\\\/premio-madre-ejemplar-2016-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/en\\\/tag\\\/premio-madre-ejemplar-2016-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Premio \u201cMadre Ejemplar 2016\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/en\\\/\",\"name\":\"Fundaci\u00f3n Microfinanzas BBVA\",\"description\":\"Fundaci\u00f3n Microfinanzas BBVA\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/en\\\/#organization\"},\"alternateName\":\"Fundaci\u00f3n Microfinanzas BBVA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/en\\\/#organization\",\"name\":\"Fundaci\u00f3n Microfinanzas BBVA\",\"alternateName\":\"Fundaci\u00f3n Microfinanzas BBVA\",\"url\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/favicon.png\",\"width\":130,\"height\":130,\"caption\":\"Fundaci\u00f3n Microfinanzas BBVA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fundacionmicrofinanzasbbva.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fundacionmicrofinanzasbbva\\\/\",\"https:\\\/\\\/x.com\\\/FMBBVA\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundaci\u00f3n-microfinanzas-bbva\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Premio \u201cMadre Ejemplar 2016\u201d archivos - Fundaci\u00f3n Microfinanzas BBVA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fundacionmicrofinanzasbbva.org\/en\/tag\/premio-madre-ejemplar-2016-en\/","og_locale":"en_US","og_type":"article","og_title":"Premio \u201cMadre Ejemplar 2016\u201d archivos - Fundaci\u00f3n Microfinanzas BBVA","og_url":"https:\/\/www.fundacionmicrofinanzasbbva.org\/en\/tag\/premio-madre-ejemplar-2016-en\/","og_site_name":"Fundaci\u00f3n Microfinanzas BBVA","og_image":[{"width":130,"height":130,"url":"https:\/\/www.fundacionmicrofinanzasbbva.org\/wp-content\/uploads\/2017\/01\/favicon.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@FMBBVA","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/en\/tag\/premio-madre-ejemplar-2016-en\/","url":"https:\/\/www.fundacionmicrofinanzasbbva.org\/en\/tag\/premio-madre-ejemplar-2016-en\/","name":"Premio \u201cMadre Ejemplar 2016\u201d archivos - Fundaci\u00f3n Microfinanzas BBVA","isPartOf":{"@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/en\/tag\/premio-madre-ejemplar-2016-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/en\/tag\/premio-madre-ejemplar-2016-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fundacionmicrofinanzasbbva.org\/en\/"},{"@type":"ListItem","position":2,"name":"Premio \u201cMadre Ejemplar 2016\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/en\/#website","url":"https:\/\/www.fundacionmicrofinanzasbbva.org\/en\/","name":"Fundaci\u00f3n Microfinanzas BBVA","description":"Fundaci\u00f3n Microfinanzas BBVA","publisher":{"@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/en\/#organization"},"alternateName":"Fundaci\u00f3n Microfinanzas BBVA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fundacionmicrofinanzasbbva.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/en\/#organization","name":"Fundaci\u00f3n Microfinanzas BBVA","alternateName":"Fundaci\u00f3n Microfinanzas BBVA","url":"https:\/\/www.fundacionmicrofinanzasbbva.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.fundacionmicrofinanzasbbva.org\/wp-content\/uploads\/2017\/01\/favicon.png","contentUrl":"https:\/\/www.fundacionmicrofinanzasbbva.org\/wp-content\/uploads\/2017\/01\/favicon.png","width":130,"height":130,"caption":"Fundaci\u00f3n Microfinanzas BBVA"},"image":{"@id":"https:\/\/www.fundacionmicrofinanzasbbva.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fundacionmicrofinanzasbbva\/","https:\/\/x.com\/FMBBVA","https:\/\/www.linkedin.com\/company\/fundaci\u00f3n-microfinanzas-bbva\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/en\/wp-json\/wp\/v2\/tags\/1292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.fundacionmicrofinanzasbbva.org\/en\/wp-json\/wp\/v2\/posts?tags=1292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}